{"id":5510,"date":"2024-03-24T01:36:44","date_gmt":"2024-03-23T23:36:44","guid":{"rendered":"https:\/\/misto.biz.ua\/lviv\/company\/kim-kimchi-korean-bbq-lviv\/"},"modified":"2024-03-24T01:36:44","modified_gmt":"2024-03-23T23:36:44","slug":"kim-kimchi-korean-bbq-lviv","status":"publish","type":"company","link":"https:\/\/misto.biz.ua\/lviv\/company\/kim-kimchi-korean-bbq-lviv\/","title":{"rendered":"Kim Kimchi Korean BBQ (\u041b\u044c\u0432\u0456\u0432)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":5511,"comment_status":"closed","ping_status":"closed","template":"","comcat":[44],"class_list":["post-5510","company","type-company","status-publish","has-post-thumbnail","hentry","comcat-restaurant"],"acf":[],"_links":{"self":[{"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/company\/5510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/company"}],"about":[{"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/types\/company"}],"replies":[{"embeddable":true,"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/comments?post=5510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/media\/5511"}],"wp:attachment":[{"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/media?parent=5510"}],"wp:term":[{"taxonomy":"comcat","embeddable":true,"href":"https:\/\/misto.biz.ua\/lviv\/wp-json\/wp\/v2\/comcat?post=5510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}